{"id":27522,"date":"2017-12-27T10:00:05","date_gmt":"2017-12-27T09:00:05","guid":{"rendered":"http:\/\/pix.house\/?p=27522"},"modified":"2017-12-27T10:00:05","modified_gmt":"2017-12-27T09:00:05","slug":"fyrtel_podsumowanie","status":"publish","type":"post","link":"https:\/\/pix.house\/en\/fyrtel_podsumowanie\/","title":{"rendered":"M\u00f3j fyrtel\/Moja przestrze\u0144 | podsumowanie"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row section vc_row-fluid\" style=' padding-top:2px; text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\">Zako\u0144czy\u0142a si\u0119 p\u00f3\u0142roczna przygoda z warsztatami <strong>M\u00f3j Fyrtel \/ Moja przestrze\u0144<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Na spotkaniach uczestnicy zg\u0142\u0119bili wiedz\u0119 dotycz\u0105c\u0105 fotografii dokumentalnej. Jakie efekty przynios\u0142a ich praca na w\u0142asnym d\u0142ugoterminowym projektem?<\/p>\n<p style=\"text-align: justify;\">Stworzyli\u015bmy wsp\u00f3lnie dokumentalny obraz naszej przestrzeni. Przestrzeni rozumianej nie wprost &#8211; jako miejsce, ale jako co\u015b, co w gruncie rzeczy jest dla nas najwa\u017cniejsze.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>W warsztatach i wystawie wzi\u0119li udzia\u0142:<\/strong><\/p>\n<p style=\"text-align: justify;\">Magdalena Orylska, S\u0142awomir Brd\u0119k, Maciej Podg\u00f3rski, Piotr Zar\u00f3wny , Artur Kujawski, Agnieszka Niemczyk, El\u017cbieta Adamska, Krzysztof Grabara, Damian Nowicki, Miko\u0142aj Konkiewicz, Norbert Oksza Strzelecki, \u0141ukasz Kotecki, \u0141ukasz Zakrzewski, Katarzyna Kubiak, Igor Le\u0144ski, Magda Wo\u0142k, Agnieszka Hinc, Joanna Czarnota-Mielcarek, Artur Kucharczak, Pawe\u0142 Hryniewicz, Katarzyna Dudzic<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Wystawa to r\u00f3wnie\u017c czas podsumowania prac nad\u00a0<a href=\"http:\/\/pix.house\/en\/portfolio_page\/spoleczne\/\" target=\"_blank\" rel=\"noopener\"><strong>Archiwum Spo\u0142ecznym Wielkopolska\/Teraz<\/strong><\/a>. Do naszych zbior\u00f3w trafi\u0142o 150 archiwalnych fotografii z Poznania i regionu.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>PROWADZENIE WARSZTAT\u00d3W:<\/strong><\/p>\n<p style=\"text-align: justify;\">Adrian Wykrota | <a href=\"http:\/\/adrianwykrota.com\" target=\"_blank\" rel=\"noopener\">http:\/\/adrianwykrota.com<\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>GO\u015aCIE \/ WSP\u00d3\u0141PROWADZ\u0104CY:<\/strong><\/p>\n<p style=\"text-align: justify;\">Mariusz Forecki | <a href=\"http:\/\/forecki.pl\" target=\"_blank\" rel=\"noopener\">www.forecki.pl<\/a><\/p>\n<p style=\"text-align: justify;\">Micha\u0142 Adamski | <a href=\"http:\/\/www.michaladamski.com.pl\" target=\"_blank\" rel=\"noopener\">www.michaladamski.com.pl<\/a><\/p>\n<p style=\"text-align: justify;\">Micha\u0142 Sita | <a href=\"http:\/\/michalsita.com\" target=\"_blank\" rel=\"noopener\">http:\/\/michalsita.com<\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><em><strong>PROJEKT FINANSOWANY W RAMACH STYPENDIUM ARTYSTYCZNEGO MINISTRA KULTURY I DZIEDZICTWA NARODOWEGO<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.mkidn.gov.pl\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26075\" src=\"http:\/\/pix.house\/wp-content\/uploads\/2017\/06\/mkidn_01_cmyk-150x150.jpg\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" srcset=\"http:\/\/pix.house\/wp-content\/uploads\/2017\/06\/mkidn_01_cmyk-150x150.jpg 150w, http:\/\/pix.house\/wp-content\/uploads\/2017\/06\/mkidn_01_cmyk-150x150-100x100.jpg 100w\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n\n\t\t<\/div>\n\t<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong>Zdj\u0119cia z warsztat\u00f3w i wystawy:\u00a0<\/strong><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/20935102_1937692779810754_3275572623889146273_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/20934151_1937692726477426_6327653324042730773_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/20901021_1937693023144063_5363640682556598054_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/20900985_1937692823144083_2424014591912388422_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/20900591_1937692959810736_7223616246790524263_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/20989014_1937692649810767_3913597633304510509_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/21015784_1937692903144075_4616481714981594759_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:762px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/21765521_1953154528264579_7485957105639842582_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/21768682_1953154571597908_1845578704581973031_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/21768790_1953154584931240_4781573856181088719_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:775px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/21768905_1953154581597907_3919515942444970031_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/21950125_1953154521597913_2405143757902668478_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:761px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/22042348_1953154524931246_7977694173028676504_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:731px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/22792160_1967428663503832_3306491735394700819_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:734px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/22829630_1967428726837159_7659863682904938702_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:735px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/22829819_1967428813503817_4429128063026742343_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/22859836_1968320786747953_1584238388802578082_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:732px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/22861597_1967428776837154_1823324348764208393_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/23004429_1968320836747948_6372963578717842167_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:745px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/23456419_1974641516115880_1361861749931718826_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/23456517_1974641512782547_2188118381210425885_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:745px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/23467270_1974641602782538_4695444783370214230_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:766px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/23467488_1974641649449200_2559899751495259670_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/23511032_1974641719449193_8487798576990606204_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/23511445_1974641609449204_7248649122596511934_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/23550007_1974641716115860_1327331220351315986_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:775px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/23550234_1974641509449214_3434890350901838096_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/23550983_1974641606115871_4281367155145534704_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:766px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/SlBr_20171112_0425.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:766px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/SlBr_20171112_0401.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/SlBr_20171112_0403.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:775px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/SlBr_20171112_0404.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/SlBr_20171112_0422.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR5033.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR5039.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR5046.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR5051.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR5054.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR5060.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:751px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/24958915_10213738740355276_1495085328264709775_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:751px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/24958892_10213738738075219_4361794729040142152_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:751px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25182276_10213738742635333_2118701407389868146_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:751px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/24955686_1989324611314237_8316360781641789520_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/24955783_1989325041314194_2156189065785760730_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:751px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/24958777_1989324277980937_1327852375430511415_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/24958937_1989325111314187_2859078922840595721_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/24959007_1989324994647532_4276030663486818979_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:751px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/24959034_1989324681314230_1559758969772454478_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25073185_1989324801314218_3300041750031065894_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:751px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25073219_1989324581314240_2032715759303282346_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25073231_1989324907980874_7227163016438056548_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:751px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25073242_1989324464647585_2766236307026645620_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25073294_1989324944647537_8987269807005155118_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:751px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25073330_1989324547980910_4741766335100376845_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:751px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25073397_1989324164647615_4534114801824301304_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:784px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25074763_1989324741314224_7437898874112674340_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25074897_1989325081314190_741895705208967360_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:751px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25075153_1989324491314249_3534276760908751004_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:751px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25075219_1989324137980951_1898422287499710508_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:751px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25075230_1989324187980946_8288551341489490667_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:751px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25182100_1989324247980940_8206821257817732443_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25182204_1989324841314214_1821298815999844069_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:756px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25188613_1989324761314222_4677938288035525738_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:751px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25188614_1989324357980929_7334724134310410506_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25188666_1989324714647560_3352749151145449693_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25188834_1989324697980895_480656683001152924_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:760px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25188852_1989324874647544_6584195106551671529_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25311219_1989324784647553_6371565893512359906_o.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:751px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/25352145_1989324437980921_8977959915311763440_o.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div     class=\"vc_row wpb_row vc_inner section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong>Projekty uczestnik\u00f3w:\u00a0<\/strong><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Agnieszka Niemczyk | (Fe)male gaze<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Stara\u0142am si\u0119 spojrze\u0107 na m\u0119\u017cczyzn troch\u0119 tak jak tradycyjnie w naszej kulturze m\u0119\u017cczy\u017ani patrz\u0105 na kobiety. Modele na moich zdj\u0119ciach s\u0105 delikatni, bezbronni i \u0142agodni. Fotografowa\u0142am bohater\u00f3w swojego projektu w niezbyt \u201cm\u0119skim\u201c antura\u017cu. My\u015bl\u0119, \u017ce stereotypy p\u0142ci s\u0105 bardzo krzywdz\u0105ce i chcia\u0142aby, \u017ceby ka\u017cda osoba mog\u0142a wybra\u0107 z genderowego spektrum to, co jej najbardziej odpowiada.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Agnieszka_Niemczyk3-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Agnieszka_Niemczyk1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Agnieszka_Niemczyk_2.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Norbert Oksza Strzelecki | Zanikanie<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Powoli zacz\u0105\u0142 zanika\u0107, kawa\u0142ek po kawa\u0142ku, gdy moi Dziadkowie odeszli 30 lat temu. Dom. Pami\u0119tam, jak b\u0119d\u0105c dzieckiem zasiada\u0142em przy du\u017cym, masywnym okr\u0105g\u0142ym stole w oczekiwaniu na jajka po wiede\u0144sku, kt\u00f3re Babcia robi\u0142a za ka\u017cdym razem gdy odwiedza\u0142em ich po szkole. Na blacie le\u017ca\u0142a lustrzana obrotowa taca. Godzinami mog\u0142em te\u017c siedzie\u0107 ws\u0142uchany w historie o koniach, kt\u00f3re Babcia kiedy\u015b mia\u0142a. Mam te\u017c silne wspomnienie Dziadka ucz\u0105cego mnie gry w szachy na ma\u0142ej, sk\u0142adanej szachownicy magnetycznej. Dziadek w monoklu, z aparatem s\u0142uchowym wczepionym w kieszonk\u0119 niczym kwiat w butonierk\u0119. \u00a0Mia\u0142em zaledwie 10 lat. Teraz Dom znika. Tapety uwolnione od wilgotnych, odrapanych \u015bcian. Kiedy\u015b-bia\u0142e firany poszarza\u0142e od py\u0142u, go\u0142\u0119bie i osy zaw\u0142aszczaj\u0105ce coraz to nowe przestrzenie. Czuj\u0119, jakby Dom wci\u0105\u017c czeka\u0142 na mnie, \u017cebym przywr\u00f3ci\u0142 go do \u017cycia, do jego dawnej \u015bwietno\u015bci.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Norbert_Oksza_Strzelecki_4.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Norbert_Oksza_Strzelecki_5-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Norbert_Oksza_Strzelecki_3.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Norbert_Oksza_Strzelecki_2.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Norbert_Oksza_Strzelecki_1.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div>\n\t<div class=\"wpb_video_widget wpb_content_element vc_clearfix   vc_video-aspect-ratio-169 vc_video-el-width-100 vc_video-align-left\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"wpb_video_wrapper\"><iframe loading=\"lazy\" title=\"Etiuda Rodzinna | Norbert Oksza Strzelecki\" width=\"413\" height=\"310\" src=\"https:\/\/www.youtube.com\/embed\/yH_YIuuSEew?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n\t\t<\/div>\n\t<\/div>\n<div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Joanna Czarnota-Mielcarek | M\u0142ode Wilki<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Zdj\u0119cia s\u0105 cz\u0119\u015bci\u0105 cyklu i przedstawiaj\u0105 pasj\u0119 m\u0142odych ludzi, sp\u0119dzaj\u0105cych sw\u00f3j wolny czas na zbi\u00f3rkach harcerskich. Bohaterami ca\u0142ej opowie\u015bci s\u0105 g\u0142\u00f3wnie Szymon i Kuba \u2013 bracia, kt\u00f3rzy wyra\u017anie widz\u0105 swoj\u0105 przysz\u0142o\u015b\u0107 w mundurze. Fotografie zosta\u0142y wykonane na zbi\u00f3rce 7 Staromiejskiej Gromady Zuchowej \u201eBia\u0142e Wilki\u201d oraz 165 Pozna\u0144skiej Dru\u017cynie Starszoharcerskiej \u201eCanis Lupus\u201d.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Joanna_Czarnota-Mielcarek_1-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:756px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Joanna_Czarnota-Mielcarek_2.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Joanna_Czarnota-Mielcarek_3.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Joanna_Czarnota-Mielcarek_4.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Joanna_Czarnota-Mielcarek_5.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Maciej Podg\u00f3rski | Kobieta samotna <\/b><\/p>\n<p><span style=\"font-weight: 400;\">Przychodzi taki czas, kiedy z grona znajomych, przyjaci\u00f3\u0142 i rodziny pozostaje coraz mniejsza grupa. Ten czas czeka nas wszystkich i towarzysz\u0105ce mu uczucia nie zawsze s\u0105 w pe\u0142ni pozytywne.Uczucie na kt\u00f3rym skupi\u0142em si\u0119 podczas projektu to samotno\u015b\u0107 i towarzysz\u0105ca jej rutyna. Oczekiwanie na spotkanie z Rodzin\u0105 daje energi\u0119 do codziennego wstawania z \u0142\u00f3\u017cka, a rutyna pomaga t\u0142umi\u0107 rosn\u0105c\u0105 t\u0119sknot\u0119.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/maciej_podg\u00f3rski_1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/maciej_podg\u00f3rski_2-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/maciej_podg\u00f3rski_3.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/maciej_podg\u00f3rski_4.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Artur Kucharczak | Pieczarka Wielichowo<\/b><\/p>\n<p><span style=\"font-weight: 400;\">LKP Pieczarka Wielichowo, klub pi\u0142karski graj\u0105cy obecnie w B klasie &#8211; najni\u017cszej lidze pi\u0142ki no\u017cnej okr\u0119gu wielkopolskiego.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Artur_Kucharczak_1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Artur_Kucharczak_2-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Artur_Kucharczak_3.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Artur_Kucharczak_4.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Artur_Kucharczak_5.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Artur_Kucharczak_6.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Artur_Kucharczak_7.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Artur_Kucharczak_8.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Artur_Kucharczak_9.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Artur Kujawski | \u2013 temat rzeka \u2013<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Zaczynamy o brzasku, nim promienie s\u0142o\u0144ca leniwe wyci\u0105gn\u0105 r\u0119k\u0119 znad horyzontu, a ko\u0144czymy po zmroku, gdy \u015bwie\u017co zadomowiona ciemno\u015b\u0107 przecinana jest ostrymi \u015bwiat\u0142ami szperaczy. Rzeka jest cierpliwsza od najstarszego drzewa. Przetrwa wszystko i pozostanie na d\u0142ugo po ostatnim \u017cywym organizmie na ziemi.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"> \u2026 niewykorzystany krwiobieg naszego kraju \u2026<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/artur_kujawski_1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/artur_kujawski_2.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/artur_kujawski_3.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/artur_kujawski_4-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/artur_kujawski_5.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/artur_kujawski_6.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Ela Adamska | Urz\u0119dnik te\u017c cz\u0142owiek<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Przez ostatnie 7 lat pracowa\u0142am w Urz\u0119dzie Miasta Poznania. Moja pierwsza doros\u0142a praca i to od razu do emerytury. \u00a0<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Na swoich zdj\u0119ciach pokazuj\u0119 to, czego nie wida\u0107 z perspektywy klienta (nie petenta!). <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Praca urz\u0119dnika to nie tylko kawa i ciasto. Praca urz\u0119dnika to te\u017c przestarza\u0142y sprz\u0119t, kolejki niezadowolonych klient\u00f3w, s\u0142abe warunki pracy, marna p\u0142aca. <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Ju\u017c tam ju\u017c nie pracuj\u0119.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Ela_Adamska_-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:752px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Ela_Adamska_-2.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:889px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Ela_Adamska_-3.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Ela_Adamska_-4-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Ela_Adamska_-5.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Ela_Adamska_-6.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Piotr Zar\u00f3wny | Gmina <\/b><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Jaki jest obraz wsi i jej mieszka\u0144c\u00f3w? Czy pochodzenie ze wsi jest obci\u0105\u017ceniem, a mo\u017ce to w\u0142a\u015bnie tutaj \u017cyje si\u0119 troch\u0119 wolniej, oddycha si\u0119 swobodniej, zna si\u0119 ka\u017cdego s\u0105siada? Z przyjemno\u015bci\u0105 przygl\u0105dam si\u0119 i dokumentuj\u0119, jak funkcjonuj\u0105 ma\u0142e wsp\u00f3lnoty w gminie Oborniki.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Piotr-Zar\u00f3wny_0036.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Piotr-Zar\u00f3wny_-0192.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Piotr-Zar\u00f3wny_-0280-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Piotr-Zar\u00f3wny_-0205.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Piotr-Zar\u00f3wny_-0475.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Piotr-Zar\u00f3wny_2095.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Piotr-Zar\u00f3wny_2934.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Piotr-Zar\u00f3wny_-2954.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Piotr-Zar\u00f3wny_-8948.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Piotr-Zar\u00f3wny_-4310.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Miko\u0142aj Konkiewicz | Bliskie spotkania ka\u017cdego stopnia<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Trzystopniowa skala bliskich spotka\u0144 z obcymi formami \u017cycia opracowana przez J. Allen&#8217;a Hynek&#8217;a obejmuje: dostrze\u017cenie \u015bwiate\u0142 lub obiekt\u00f3w o nieznanym pochodzeniu (bliskie spotkania pierwszego stopnia), obcowanie z artefaktami tajemniczej natury, takimi jak np. \u015blady czy kr\u0119gi w zbo\u017cu (bliskie spotkania drugiego stopnia), bezpo\u015bredni kontakt z za\u0142og\u0105 UFO (bliskie spotkania trzeciego stopnia). <\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:375px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Miko\u0142aj_Konkiewicz_3.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:667px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Miko\u0142aj_Konkiewicz_2-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:375px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Miko\u0142aj_Konkiewicz_1.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Igor Le\u0144ski | SORtownia<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Od zawsze na Szpitalnych Oddzia\u0142ach Ratunkowych obowi\u0105zuje zasada, \u017ce przyjmuje si\u0119 pacjent\u00f3w wed\u0142ug stanu zdrowia, a nie kolejno\u015bci zg\u0142oszenia, st\u0105d na przyj\u0119cie i diagnostyk\u0119 trzeba czeka\u0107 niekiedy nawet kilka godzin. Konieczno\u015b\u0107 wype\u0142niania stert dokument\u00f3w, nagminnie pojawiaj\u0105cy si\u0119 nietrze\u017awi przywo\u017ceni przez patrole policji, czy \u00a0osoby niewymagaj\u0105ce medycznych czynno\u015bci ratunkowych, kt\u00f3re powinny zosta\u0107 przyj\u0119te u lekarza rodzinnego, powoduj\u0105 niepotrzebne kolejki i konieczno\u015b\u0107 d\u0142ugiego oczekiwania przez chorych. <\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/igor_lenski_1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/igor_lenski_3.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/igor_lenski_2-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/igor_lenski_4.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/igor_lenski_5.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>\u0141ukasz Kotecki | Widoczne\/Niewidzialne<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Wszystko zacz\u0119\u0142o si\u0119 od powrotu. Porzuci\u0142em pocz\u0105tkowy pomys\u0142, by kontynuowa\u0107 fotografowanie przyrody w otoczeniu ekspansji cz\u0142owieka. Zaw\u0142aszczone przestrzenie, porzucane lub nie b\u0119d\u0105ce pod jego sta\u0142ym nadzorem, powoli wracaj\u0105 tam gdzie by\u0142y wcze\u015bniej. Te pilnowane za\u015b, dekorowane s\u0105 z dba\u0142o\u015bci\u0105 w to co wcze\u015bniej stamt\u0105d znikn\u0119\u0142o, by stworzy\u0107 pozory harmonii i jedno\u015bci. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Taka chaotyczna natura i uporz\u0105dkowany cz\u0142owiek, sta\u0142y si\u0119 dla mnie metafor\u0105 oboj\u0119tno\u015bci, prze\u017aroczysto\u015bci, a mo\u017ce r\u00f3wnie\u017c niech\u0119ci wobec tego co wymyka si\u0119 z wyidealizowanych, estetycznych, sztucznych wzor\u00f3w. My\u015bl\u0105c o tym pojawia si\u0119 pytanie o rzeczywist\u0105 warto\u015b\u0107 tego co naturalne.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:695px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/\u0142ukasz_kotecki_1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/\u0142ukasz_kotecki_3-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/\u0142ukasz_kotecki_2.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Krzysiek Grabara | (Nie)zmiennie<\/b><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">(Nie)zmiennie \u2013 czyli w poszukiwaniu tego co zmienia si\u0119 oraz tego co pozostaje niezmienne na polskiej wsi. Odkrywaj\u0105c na nowo polsk\u0105 wie\u015b mia\u0142em wra\u017cenie, \u017ce niekt\u00f3re aspekty nie zmieni\u0105 si\u0119 nigdy. <\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:753px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Krzysiek_Grabara_1-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:749px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Krzysiek_Grabara_2.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:753px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Krzysiek_Grabara_3.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:749px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Krzysiek_Grabara_4.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:748px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Krzysiek_Grabara_5.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Krzysiek_Grabara_6.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:753px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Krzysiek_Grabara_7.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Krzysiek_Grabara_8.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Magdalena Orylska<\/b><span style=\"font-weight: 400;\"> | <\/span><b>Mi\u0119dzy s\u0142owami<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Seria inspirowana beztroskim dzieci\u0144stwem. Odkrywa drog\u0119 do\u015bwiadczania, poznawania i czerpania rado\u015bci z otaczaj\u0105cego \u015bwiata. Anonimowo\u015b\u0107 bohater\u00f3w nie jest przypadkowa. Uchwycone kadry pokazuj\u0105 dwoje dzieci i ich wzajemn\u0105 relacj\u0119 oraz relacj\u0119 ze \u015brodowiskiem w kt\u00f3rym przebywaj\u0105.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Magdalena_Orylska_1-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Magdalena_Orylska_2.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Magdalena_Orylska_3.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Magdalena_Orylska_4.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Magdalena_Orylska_5.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Magdalena_Orylska_6.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Pawe\u0142 Hryniewicz | Elementy krajobrazu<\/b><\/p>\n<p><span style=\"font-weight: 400;\">&#8222;Elementy krajobrazu&#8221; to fotografie \u00a0obiekt\u00f3w porzuconych w przestrzeni miejskiej. Niepotrzebne, zdegradowane, nie pe\u0142ni\u0105 ju\u017c swoich pierwotnych funkcji. Jednocze\u015bnie nie zosta\u0142y zaadaptowane do nowych cel\u00f3w, pozostaj\u0105c bezu\u017cytecznymi elementami kszta\u0142towanego przez cz\u0142owieka otoczenia. <\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:621px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/pawel_hryniewicz_1-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:622px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/pawel_hryniewicz_2.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:618px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/pawel_hryniewicz_3.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:621px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/pawel_hryniewicz_4.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:620px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/pawel_hryniewicz_5.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:620px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/pawel_hryniewicz_6.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>S\u0142awomir Brd\u0119k | \u00a0Fight Club<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Temat stary jak \u015bwiat i oklepany fotograficznie w ka\u017cdy mo\u017cliwy spos\u00f3b. Dlaczego ludzie walcz\u0105? \u00a0Bo takie maj\u0105 potrzeby, zami\u0142owania, \u017cy\u0142k\u0119 rywalizacji. Chc\u0105 by\u0107 lepsi, sprawniejsi i chc\u0105 pi\u0105\u0107 si\u0119 wy\u017cej. Zaczynaj\u0105 od ma\u0142ych turniej\u00f3w, kt\u00f3re s\u0105 trampolin\u0105 do du\u017cych gali sport\u00f3w walki\u2026 \u00a0<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:769px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/S\u0142awek_Brd\u0119k_1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:751px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/S\u0142awek_Brd\u0119k_2.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/S\u0142awek_Brd\u0119k_3-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:756px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/S\u0142awek_Brd\u0119k_4.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/S\u0142awek_Brd\u0119k_5.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:781px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/S\u0142awek_Brd\u0119k_6.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Katarzyna Dudzic | Troligoblin<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Troligoblin to pseudonim artystyczny duetu: Marty i Su. Par\u0119 po\u0142\u0105czy\u0142a wsp\u00f3lna pasja do\u00a0<\/span><span style=\"font-weight: 400;\">wyst\u0119p\u00f3w cyrkowych i \u017conglerki. Razem wyst\u0119puj\u0105 jako arty\u015bci uliczni, na scenie a tak\u017ce na\u00a0<\/span><span style=\"font-weight: 400;\">r\u00f3\u017cnych eventach i festiwalach. Jakie maj\u0105 podej\u015bcie do \u017cycia? Czy \u015bwiat \u201eza kulisami\u201d dla\u00a0<\/span><span style=\"font-weight: 400;\">obojga wygl\u0105da tak samo?<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:667px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Katarzyna_Dudzic_1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:667px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Katarzyna_Dudzic_2-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:667px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Katarzyna_Dudzic_3.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:667px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Katarzyna_Dudzic_4.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:667px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Katarzyna_Dudzic_5.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:667px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Katarzyna_Dudzic_6.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Damian Nowicki | Pan Krzysztof <\/b><\/p>\n<p><span style=\"font-weight: 400;\">Pan Krzysztof urodzi\u0142 si\u0119 w 1929 roku, w domu otrzyma\u0142 wychowanie w duchu patriotycznym. Kiedy sko\u0144czy\u0142a si\u0119 II wojna \u015bwiatowa jako nastolatek walczy\u0142 z UB w obronie religii w szko\u0142ach. Wsp\u00f3lnie z \u017con\u0105 sp\u0119dzi\u0142 ponad 60 lat \u017cycia, jej \u015bmier\u0107 by\u0142a ogromnym ciosem dla niego. Wielk\u0105 pasj\u0105 Pana Krzysztofa by\u0142a polityka, grafiki Zdzis\u0142awa Beksi\u0144skiego oraz koty. Na pytanie, co chcia\u0142by przekaza\u0107 m\u0142odym pokoleniom, powiedzia\u0142: niech kochaj\u0105 poezj\u0119, niech kochaj\u0105 literatur\u0119, niech kochaj\u0105 Polsk\u0119. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pan Krzysztof odszed\u0142 w pa\u017adzierniku 2017 roku.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Damian_Nowicki_1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Damian_Nowicki_3.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Damian_Nowicki_4-1.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>\u0141ukasz Zakrzewski | Na morzu<\/b><\/p>\n<p><span style=\"font-weight: 400;\">W momencie gdy to czytasz ponad p\u00f3\u0142tora miliona marynarzy p\u0142ywa na statkach na morzach i oceanach ca\u0142ego \u015bwiata. S\u0105 w porcie albo na morzu, \u0142aduj\u0105 i roz\u0142adowuj\u0105 towary, pracuj\u0105 na pok\u0142adzie, pe\u0142ni\u0105 wacht\u0119 albo \u015bpi\u0105. Te 1,5 miliona ludzi przewozi oko\u0142o 90 % wszystkich towar\u00f3w w transporcie mi\u0119dzynarodowym. Ograniczeni wielko\u015bci\u0105 statku, cz\u0119sto bez dost\u0119pu do internetu i telefonu, sp\u0119dzaj\u0105 wi\u0119ksz\u0105 cz\u0119\u015b\u0107 swojego \u017cycia na morzu, dbaj\u0105c by towary dociera\u0142y do punktu przeznaczenia, do nas.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/\u0141ukasz_Zakrzewski_1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/\u0141ukasz_Zakrzewski_2.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/\u0141ukasz_Zakrzewski_3.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:759px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/\u0141ukasz_Zakrzewski_4.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/\u0141ukasz_Zakrzewski_5.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/\u0141ukasz_Zakrzewski_6.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/\u0141ukasz_Zakrzewski_7.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:760px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/\u0141ukasz_Zakrzewski_8-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/\u0141ukasz_Zakrzewski_9.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/\u0141ukasz_Zakrzewski_10.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/\u0141ukasz_Zakrzewski_11.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/\u0141ukasz_Zakrzewski_12.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/\u0141ukasz_Zakrzewski_13.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/\u0141ukasz_Zakrzewski_14.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/\u0141ukasz_Zakrzewski_15.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Magda Wo\u0142k | bad days<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Bad days to zbi\u00f3r zdj\u0119\u0107, kt\u00f3re \u0142\u0105czy jedna cecha &#8211; z\u0142y dzie\u0144. Znu\u017cenie, zaspanie, z\u0142o\u015b\u0107, zamy\u015blenie, oboj\u0119tno\u015b\u0107&#8230; Ka\u017cdy z nas miewa z\u0142e dni. <\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:754px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/2.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:754px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/4.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:754px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/5.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:787px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/2017_08_pan800_009.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:754px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/10270001.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Katarzyna Kubiak | Charlotte <\/b><\/p>\n<p><span style=\"font-weight: 400;\">Charlotte to pseudonim artystyczny bohaterki, a w\u0142a\u015bciwie bohatera mojego projektu. Jest to opowie\u015b\u0107 o m\u0119\u017cczy\u017anie, kt\u00f3ry na co dzie\u0144 jest konduktorem poci\u0105gu. Jak ka\u017cdy z nas prowadzi na poz\u00f3r normalne \u017cycie. Jednak kiedy przychodzi noc staje si\u0119 zupe\u0142nie kim\u015b innym. Charlotte to jedna z warszawskich Draq Queen, kt\u00f3r\u0105 cz\u0119sto mo\u017cecie spotka\u0107 zar\u00f3wno w klubach jak i na wielu wydarzeniach zwi\u0105zanych z ruchem LGTB.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Katarzyna_Kubiak_1-1.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Katarzyna_Kubiak_2.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Katarzyna_Kubiak_3.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Katarzyna_Kubiak_4.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/Katarzyna_Kubiak_5.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Agnieszka Hinc | Telefony z lud\u017ami<\/b><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div>\n\t<div class=\"wpb_video_widget wpb_content_element vc_clearfix   vc_video-aspect-ratio-169 vc_video-el-width-100 vc_video-align-left\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"wpb_video_wrapper\"><iframe loading=\"lazy\" title=\"Telefony z lud\u017ami\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/2WOJc8PnZKE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n\t\t<\/div>\n\t<\/div>\n<div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><b>Dokumentacja ekspozycji:\u00a0<\/b><\/p>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><div class='qode_image_gallery_no_space light highlight_active'><div class='qode_image_gallery_holder' style='height: 500px;'><ul><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR6118.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR6114.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR6083.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR6085.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR6088.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR6090.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR6094.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR6099.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR6101.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR6104.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR6107.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR6110.jpg\" alt=\"\" \/><\/div><\/li><li><div style=\"height: 500px; width:750px;\"><img decoding=\"async\" src=\"https:\/\/pix.house\/wp-content\/uploads\/2017\/12\/WYKR6112.jpg\" alt=\"\" \/><\/div><\/li><\/ul><\/div><div class=\"controls\"><a class=\"prev-slide\" href=\"#\"><span class=\"arrow_carrot-left\"><\/span><\/a><a class=\"next-slide\" href=\"#\"><span class=\"arrow_carrot-right\"><\/span><\/a><\/div><\/div><div class=\"separator  normal\" style=\"border-color: #ffffff;border-width:0,5px\"><\/div><\/div><\/div><\/div><\/div><\/div><div     class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\"><b>Podzi\u0119kowania!\u00a0<\/b><\/p>\n<p style=\"text-align: justify;\">Serdecznie dzi\u0119kuj\u0119 wszystkim <strong>uczestnikom <\/strong>warsztat\u00f3w &#8211; r\u00f3wnie\u017c tym, kt\u00f3rym z r\u00f3\u017cnych powod\u00f3w nie uda\u0142o si\u0119 dotrwa\u0107 do wystawy. W\u0142o\u017cyli\u015bcie kawa\u0142 serca i ogrom pracy w ten projekt. Dzi\u0119kuj\u0119!<\/p>\n<p style=\"text-align: justify;\">Chcia\u0142em r\u00f3wnie\u017c serdecznie podzi\u0119kowa\u0107 <strong>go\u015bciom<\/strong>, kt\u00f3rzy zgodzili si\u0119 przekaza\u0107 swoj\u0105 wiedz\u0119 grupie warsztatowej!<\/p>\n<p style=\"text-align: justify;\">Warsztaty nie odby\u0142yby si\u0119 bez wsparcia <strong>Ministerstwa Kultury i Dziedzictwa Narodowego<\/strong>. Serdeczne podzi\u0119kowania za stypendium.<\/p>\n<p style=\"text-align: justify;\">Warsztaty odbywa\u0142y si\u0119 w przestrzeni Fundacji PIX.HOUSE &#8211; tworzymy miejsce dla fotografii!<\/p>\n<p style=\"text-align: right;\">Adrian Wykrota<\/p>\n\n\t\t<\/div>\n\t<\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Zako\u0144czy\u0142a si\u0119 p\u00f3\u0142roczna przygoda z warsztatami M\u00f3j Fyrtel \/ Moja przestrze\u0144. Na spotkaniach uczestnicy zg\u0142\u0119bili wiedz\u0119 dotycz\u0105c\u0105 fotografii dokumentalnej. Jakie efekty przynios\u0142a ich praca na w\u0142asnym d\u0142ugoterminowym projektem? Stworzyli\u015bmy wsp\u00f3lnie dokumentalny obraz naszej przestrzeni. Przestrzeni rozumianej nie wprost - jako miejsce, ale jako co\u015b, co...","protected":false},"author":11,"featured_media":27545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[59],"tags":[],"class_list":["post-27522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-co-z-ta-fotografia"],"_links":{"self":[{"href":"https:\/\/pix.house\/en\/wp-json\/wp\/v2\/posts\/27522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pix.house\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pix.house\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pix.house\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/pix.house\/en\/wp-json\/wp\/v2\/comments?post=27522"}],"version-history":[{"count":24,"href":"https:\/\/pix.house\/en\/wp-json\/wp\/v2\/posts\/27522\/revisions"}],"predecessor-version":[{"id":27565,"href":"https:\/\/pix.house\/en\/wp-json\/wp\/v2\/posts\/27522\/revisions\/27565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pix.house\/en\/wp-json\/wp\/v2\/media\/27545"}],"wp:attachment":[{"href":"https:\/\/pix.house\/en\/wp-json\/wp\/v2\/media?parent=27522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pix.house\/en\/wp-json\/wp\/v2\/categories?post=27522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pix.house\/en\/wp-json\/wp\/v2\/tags?post=27522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}